{"id":821,"date":"2020-01-31T07:38:00","date_gmt":"2020-01-31T05:38:00","guid":{"rendered":"https:\/\/dimdini.majaslapabiznesam.lv\/fruit-logistica-berlin-2020\/"},"modified":"2026-05-28T11:48:27","modified_gmt":"2026-05-28T09:48:27","slug":"fruit-logistica-berlin-2020","status":"publish","type":"post","link":"https:\/\/dimdini.lv\/en\/fruit-logistica-berlin-2020\/","title":{"rendered":"FRUIT LOGISTICA BERLIN 2020"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Dimdi\u0146i Ltd. is pleased to participate in the international fresh produce exhibition FRUIT LOGISTICA in Berlin! We invite you to visit us and are delighted to meet with our partners and new interested parties.<\/p>\n\n<p class=\"wp-block-paragraph\">See you at FRUIT LOGISTICA BERLIN 2020<\/p>\n\n<ul class=\"wp-block-list\">\n<li>8.2. in Hall 2.1, Stand A-28. <\/li>\n<\/ul>\n\n<p class=\"wp-block-paragraph\">The exhibition takes place from February 5 to 7 at Messe Berlin.<\/p>\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>See you in Berlin! Dimdi\u0146i Ltd. is participating in one of Europe&#8217;s largest fresh produce exhibitions.<\/p>\n","protected":false},"author":1,"featured_media":823,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[21],"tags":[],"class_list":["post-821","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-uncategorized"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>FRUIT LOGISTICA BERLIN 2020 - dimdini<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dimdini.lv\/en\/fruit-logistica-berlin-2020\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"FRUIT LOGISTICA BERLIN 2020 - dimdini\" \/>\n<meta property=\"og:description\" content=\"See you in Berlin! Dimdi\u0146i Ltd. is participating in one of Europe&#039;s largest fresh produce exhibitions.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dimdini.lv\/en\/fruit-logistica-berlin-2020\/\" \/>\n<meta property=\"og:site_name\" content=\"dimdini\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Dimdini\" \/>\n<meta property=\"article:published_time\" content=\"2020-01-31T05:38:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-28T09:48:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dimdini.lv\/wp-content\/uploads\/2020\/01\/Ekranuznemums-2026-05-27-153454.png\" \/>\n\t<meta property=\"og:image:width\" content=\"810\" \/>\n\t<meta property=\"og:image:height\" content=\"758\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"haldur\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"haldur\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/dimdini.lv\\\/en\\\/fruit-logistica-berlin-2020\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dimdini.lv\\\/en\\\/fruit-logistica-berlin-2020\\\/\"},\"author\":{\"name\":\"haldur\",\"@id\":\"https:\\\/\\\/dimdini.lv\\\/en\\\/#\\\/schema\\\/person\\\/b72f91be4c2115e2444f9c1fc3a46f4e\"},\"headline\":\"FRUIT LOGISTICA BERLIN 2020\",\"datePublished\":\"2020-01-31T05:38:00+00:00\",\"dateModified\":\"2026-05-28T09:48:27+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/dimdini.lv\\\/en\\\/fruit-logistica-berlin-2020\\\/\"},\"wordCount\":58,\"publisher\":{\"@id\":\"https:\\\/\\\/dimdini.lv\\\/en\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/dimdini.lv\\\/en\\\/fruit-logistica-berlin-2020\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dimdini.lv\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/Ekranuznemums-2026-05-27-153454.png\",\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/dimdini.lv\\\/en\\\/fruit-logistica-berlin-2020\\\/\",\"url\":\"https:\\\/\\\/dimdini.lv\\\/en\\\/fruit-logistica-berlin-2020\\\/\",\"name\":\"FRUIT LOGISTICA BERLIN 2020 - dimdini\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/dimdini.lv\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/dimdini.lv\\\/en\\\/fruit-logistica-berlin-2020\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/dimdini.lv\\\/en\\\/fruit-logistica-berlin-2020\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/dimdini.lv\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/Ekranuznemums-2026-05-27-153454.png\",\"datePublished\":\"2020-01-31T05:38:00+00:00\",\"dateModified\":\"2026-05-28T09:48:27+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/dimdini.lv\\\/en\\\/fruit-logistica-berlin-2020\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/dimdini.lv\\\/en\\\/fruit-logistica-berlin-2020\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/dimdini.lv\\\/en\\\/fruit-logistica-berlin-2020\\\/#primaryimage\",\"url\":\"https:\\\/\\\/dimdini.lv\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/Ekranuznemums-2026-05-27-153454.png\",\"contentUrl\":\"https:\\\/\\\/dimdini.lv\\\/wp-content\\\/uploads\\\/2020\\\/01\\\/Ekranuznemums-2026-05-27-153454.png\",\"width\":810,\"height\":758},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/dimdini.lv\\\/en\\\/fruit-logistica-berlin-2020\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/dimdini.lv\\\/en\\\/home\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"FRUIT LOGISTICA BERLIN 2020\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/dimdini.lv\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/dimdini.lv\\\/en\\\/\",\"name\":\"Dimdi\u0146i\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/dimdini.lv\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/dimdini.lv\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/dimdini.lv\\\/en\\\/#organization\",\"name\":\"Dimdi\u0146i\",\"url\":\"https:\\\/\\\/dimdini.lv\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/dimdini.lv\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/dimdini.lv\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/dd-logo-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/dimdini.lv\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/dd-logo-scaled.jpg\",\"width\":2560,\"height\":1558,\"caption\":\"Dimdi\u0146i\"},\"image\":{\"@id\":\"https:\\\/\\\/dimdini.lv\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Dimdini\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/dimdini.lv\\\/en\\\/#\\\/schema\\\/person\\\/b72f91be4c2115e2444f9c1fc3a46f4e\",\"name\":\"haldur\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7e672b8efa1e0d258185603c2e9a82580fc902bb42347c1446961f2822702bfc?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7e672b8efa1e0d258185603c2e9a82580fc902bb42347c1446961f2822702bfc?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7e672b8efa1e0d258185603c2e9a82580fc902bb42347c1446961f2822702bfc?s=96&d=mm&r=g\",\"caption\":\"haldur\"},\"sameAs\":[\"https:\\\/\\\/dimdini.lv\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"FRUIT LOGISTICA BERLIN 2020 - dimdini","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dimdini.lv\/en\/fruit-logistica-berlin-2020\/","og_locale":"en_US","og_type":"article","og_title":"FRUIT LOGISTICA BERLIN 2020 - dimdini","og_description":"See you in Berlin! Dimdi\u0146i Ltd. is participating in one of Europe's largest fresh produce exhibitions.","og_url":"https:\/\/dimdini.lv\/en\/fruit-logistica-berlin-2020\/","og_site_name":"dimdini","article_publisher":"https:\/\/www.facebook.com\/Dimdini","article_published_time":"2020-01-31T05:38:00+00:00","article_modified_time":"2026-05-28T09:48:27+00:00","og_image":[{"width":810,"height":758,"url":"https:\/\/dimdini.lv\/wp-content\/uploads\/2020\/01\/Ekranuznemums-2026-05-27-153454.png","type":"image\/png"}],"author":"haldur","twitter_card":"summary_large_image","twitter_misc":{"Written by":"haldur"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/dimdini.lv\/en\/fruit-logistica-berlin-2020\/#article","isPartOf":{"@id":"https:\/\/dimdini.lv\/en\/fruit-logistica-berlin-2020\/"},"author":{"name":"haldur","@id":"https:\/\/dimdini.lv\/en\/#\/schema\/person\/b72f91be4c2115e2444f9c1fc3a46f4e"},"headline":"FRUIT LOGISTICA BERLIN 2020","datePublished":"2020-01-31T05:38:00+00:00","dateModified":"2026-05-28T09:48:27+00:00","mainEntityOfPage":{"@id":"https:\/\/dimdini.lv\/en\/fruit-logistica-berlin-2020\/"},"wordCount":58,"publisher":{"@id":"https:\/\/dimdini.lv\/en\/#organization"},"image":{"@id":"https:\/\/dimdini.lv\/en\/fruit-logistica-berlin-2020\/#primaryimage"},"thumbnailUrl":"https:\/\/dimdini.lv\/wp-content\/uploads\/2020\/01\/Ekranuznemums-2026-05-27-153454.png","inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/dimdini.lv\/en\/fruit-logistica-berlin-2020\/","url":"https:\/\/dimdini.lv\/en\/fruit-logistica-berlin-2020\/","name":"FRUIT LOGISTICA BERLIN 2020 - dimdini","isPartOf":{"@id":"https:\/\/dimdini.lv\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dimdini.lv\/en\/fruit-logistica-berlin-2020\/#primaryimage"},"image":{"@id":"https:\/\/dimdini.lv\/en\/fruit-logistica-berlin-2020\/#primaryimage"},"thumbnailUrl":"https:\/\/dimdini.lv\/wp-content\/uploads\/2020\/01\/Ekranuznemums-2026-05-27-153454.png","datePublished":"2020-01-31T05:38:00+00:00","dateModified":"2026-05-28T09:48:27+00:00","breadcrumb":{"@id":"https:\/\/dimdini.lv\/en\/fruit-logistica-berlin-2020\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dimdini.lv\/en\/fruit-logistica-berlin-2020\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/dimdini.lv\/en\/fruit-logistica-berlin-2020\/#primaryimage","url":"https:\/\/dimdini.lv\/wp-content\/uploads\/2020\/01\/Ekranuznemums-2026-05-27-153454.png","contentUrl":"https:\/\/dimdini.lv\/wp-content\/uploads\/2020\/01\/Ekranuznemums-2026-05-27-153454.png","width":810,"height":758},{"@type":"BreadcrumbList","@id":"https:\/\/dimdini.lv\/en\/fruit-logistica-berlin-2020\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/dimdini.lv\/en\/home\/"},{"@type":"ListItem","position":2,"name":"FRUIT LOGISTICA BERLIN 2020"}]},{"@type":"WebSite","@id":"https:\/\/dimdini.lv\/en\/#website","url":"https:\/\/dimdini.lv\/en\/","name":"Dimdi\u0146i","description":"","publisher":{"@id":"https:\/\/dimdini.lv\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dimdini.lv\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/dimdini.lv\/en\/#organization","name":"Dimdi\u0146i","url":"https:\/\/dimdini.lv\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/dimdini.lv\/en\/#\/schema\/logo\/image\/","url":"https:\/\/dimdini.lv\/wp-content\/uploads\/2026\/04\/dd-logo-scaled.jpg","contentUrl":"https:\/\/dimdini.lv\/wp-content\/uploads\/2026\/04\/dd-logo-scaled.jpg","width":2560,"height":1558,"caption":"Dimdi\u0146i"},"image":{"@id":"https:\/\/dimdini.lv\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Dimdini"]},{"@type":"Person","@id":"https:\/\/dimdini.lv\/en\/#\/schema\/person\/b72f91be4c2115e2444f9c1fc3a46f4e","name":"haldur","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/7e672b8efa1e0d258185603c2e9a82580fc902bb42347c1446961f2822702bfc?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/7e672b8efa1e0d258185603c2e9a82580fc902bb42347c1446961f2822702bfc?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7e672b8efa1e0d258185603c2e9a82580fc902bb42347c1446961f2822702bfc?s=96&d=mm&r=g","caption":"haldur"},"sameAs":["https:\/\/dimdini.lv"]}]}},"_links":{"self":[{"href":"https:\/\/dimdini.lv\/en\/wp-json\/wp\/v2\/posts\/821","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dimdini.lv\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dimdini.lv\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dimdini.lv\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/dimdini.lv\/en\/wp-json\/wp\/v2\/comments?post=821"}],"version-history":[{"count":0,"href":"https:\/\/dimdini.lv\/en\/wp-json\/wp\/v2\/posts\/821\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dimdini.lv\/en\/wp-json\/wp\/v2\/media\/823"}],"wp:attachment":[{"href":"https:\/\/dimdini.lv\/en\/wp-json\/wp\/v2\/media?parent=821"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dimdini.lv\/en\/wp-json\/wp\/v2\/categories?post=821"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dimdini.lv\/en\/wp-json\/wp\/v2\/tags?post=821"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}